{"id":683,"date":"2025-10-20T13:38:46","date_gmt":"2025-10-20T13:38:46","guid":{"rendered":"https:\/\/leyendadeolivo.com\/millenary-farga-olive-oil-milenario-500-ml\/"},"modified":"2025-11-14T12:35:55","modified_gmt":"2025-11-14T12:35:55","slug":"aceite-oliva-farga-milenario-500-ml","status":"publish","type":"page","link":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/","title":{"rendered":"Milenario"},"content":{"rendered":"\n\t<section class=\"section\" id=\"section_860293825\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"gap-59821135\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-59821135 {\n  padding-top: 80px;\n}\n@media (min-width:550px) {\n  #gap-59821135 {\n    padding-top: 100px;\n  }\n}\n@media (min-width:850px) {\n  #gap-59821135 {\n    padding-top: 140px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\" style=\"max-width:930px\" id=\"row-2094661178\">\n\n\t<div id=\"col-1687592762\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2356768151\" class=\"text doubled-font txt-m-0 italic\">\n\t\t\n<h1 data-animate=\"fadeIn\">Milenario <span class=\"small-text\">500 ml | Aceite de Oliva Farga Milenario<\/span><\/h1>\n\t\t\n<style>\n#text-2356768151 {\n  font-size: 2rem;\n  line-height: 1;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-2356768151 {\n    font-size: 2.5rem;\n  }\n}\n@media (min-width:850px) {\n  #text-2356768151 {\n    font-size: 2.5625rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-156661937\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-156661937 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover center-image x md-x lg-x y md-y lg-y\" id=\"image_452318838\">\n\t\t\t\t\t\t<div data-animate=\"blurIn\">\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"967\" height=\"772\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-header.jpg\" class=\"attachment-original size-original\" alt=\"Premium Olive Oil exclusive bottle\" srcset=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-header.jpg 967w, https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-header-300x240.jpg 300w, https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-header-768x613.jpg 768w\" sizes=\"auto, (max-width: 967px) 100vw, 967px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_452318838 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-452237309\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-452237309 {\n  padding-top: 40px;\n}\n@media (min-width:550px) {\n  #gap-452237309 {\n    padding-top: 80px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2946184453\" class=\"text italic txt-m-0 balance\">\n\t\t\n<p data-animate=\"fadeIn\">\u201cUn homenaje al tiempo, la pureza,<br \/>y a la propia tierra.\u201d<\/p>\n\t\t\n<style>\n#text-2946184453 {\n  font-size: 1.5rem;\n  line-height: 1.3;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-2946184453 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-1880132985\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1880132985 {\n  padding-top: 60px;\n}\n@media (min-width:550px) {\n  #gap-1880132985 {\n    padding-top: 100px;\n  }\n}\n@media (min-width:850px) {\n  #gap-1880132985 {\n    padding-top: 140px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_860293825 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1056206374\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-collapse row-full-width\"  id=\"row-1001197395\">\n\n\t<div id=\"col-828345760\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-787982114\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1200\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-left.jpg\" class=\"bg attachment-original size-original\" alt=\"Leyenda de Olivo Exclusive bottle\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-703473840\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-703473840 {\n  width: 60%;\n}\n#text-box-703473840 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-703473840 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-787982114 {\n  padding-top: 120%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1929890346\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1191450455\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1200\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-right.jpg\" class=\"bg attachment-original size-original\" alt=\"Milenario 500 ml Millenary Farga Olive Oil\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1051943042\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1051943042 {\n  width: 60%;\n}\n#text-box-1051943042 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1051943042 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1191450455 {\n  padding-top: 120%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1056206374 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_706201100\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"gap-1095642655\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1095642655 {\n  padding-top: 60px;\n}\n@media (min-width:550px) {\n  #gap-1095642655 {\n    padding-top: 100px;\n  }\n}\n@media (min-width:850px) {\n  #gap-1095642655 {\n    padding-top: 140px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\" style=\"max-width:930px\" id=\"row-1982317669\">\n\n\t<div id=\"col-716907559\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3172860953\" class=\"text\">\n\t\t\n<p>Nacido de olivos Farga milenarios, cada botella es una celebraci\u00f3n del legado y la devoci\u00f3n, un puente entre la naturaleza y la eternidad.<\/p>\n<p>Cosechado con reverencia y prensado en fr\u00edo, esta edici\u00f3n limitada de solo 1.000 botellas captura el alma del Mediterr\u00e1neo en su forma m\u00e1s pura.<\/p>\n\t\t\n<style>\n#text-3172860953 {\n  font-size: 1.5rem;\n  line-height: 1.3;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-3172860953 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-408799128\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-408799128 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"#contacto\" class=\"button primary\" >\n\t\t<span>CONT\u00c1CTANOS<\/span>\n\t<\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-180461157\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-180461157 {\n  padding-top: 60px;\n}\n@media (min-width:550px) {\n  #gap-180461157 {\n    padding-top: 100px;\n  }\n}\n@media (min-width:850px) {\n  #gap-180461157 {\n    padding-top: 120px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_706201100 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section z-index-2\" id=\"section_1982164656\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"833\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/vista-del-tronco-del-arbol-en-el-campo-3.jpg\" class=\"bg attachment- size-\" alt=\"contact us\" \/>\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<span class=\"scroll-to\" data-label=\"Scroll to: #contact\" data-bullet=\"false\" data-link=\"#contact\" data-title=\"contact\"><a name=\"contact\"><\/a><\/span>\n\t<div id=\"gap-1893728419\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1893728419 {\n  padding-top: 80px;\n}\n@media (min-width:850px) {\n  #gap-1893728419 {\n    padding-top: 100px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1679308160\">\n\n\t<div id=\"col-364659833\" class=\"col txt-m-0 small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2417709307\" class=\"text txt-m-0 italic\">\n\t\t\n<p>Contacta con nosotros<\/p>\n\t\t\n<style>\n#text-2417709307 {\n  font-size: 3rem;\n  line-height: 1.2;\n  text-align: center;\n  color: rgb(255, 255, 255);\n}\n#text-2417709307 > * {\n  color: rgb(255, 255, 255);\n}\n@media (min-width:850px) {\n  #text-2417709307 {\n    font-size: 3.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse\" style=\"max-width:850px\" id=\"row-2147482723\">\n\n\t<div id=\"col-1492021551\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(251, 251, 251);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-54348598\" class=\"text txt-m-0 italic\">\n\t\t\n<p>Tu mensaje es parte de nuestro legado<\/p>\n\t\t\n<style>\n#text-54348598 {\n  font-size: 1.5rem;\n  line-height: 1.2;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-54348598 {\n    font-size: 1.75rem;\n  }\n}\n@media (min-width:850px) {\n  #text-54348598 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1423244208\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1423244208 {\n  padding-top: 40px;\n}\n@media (min-width:550px) {\n  #gap-1423244208 {\n    padding-top: 60px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"frm_forms \" id=\"frm_form_2_container\" data-token=\"b3d15c47ab7dd183ca1501d6d0301588\">\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_pro_form \" id=\"form_contacto-form\" data-token=\"b3d15c47ab7dd183ca1501d6d0301588\">\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_screen_reader\">Contacto<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"2\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_2\" id=\"frm_hide_fields_2\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contacto-form\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_2\" name=\"frm_submit_entry_2\" value=\"b0b871dd0d\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/683\" \/><div id=\"frm_field_11_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container frm12 frm_first\">\r\n\t<label for=\"field_qh4icy2\" id=\"field_qh4icy2_label\" class=\"frm_primary_label\">Nombre\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input  type=\"text\" id=\"field_qh4icy2\" name=\"item_meta[11]\" value=\"\"  placeholder=\"Nombre *\" data-reqmsg=\"Nombre no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Nombre no es v\u00e1lido\" aria-invalid=\"false\"   \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_12_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container frm_full\">\r\n\t<label for=\"field_29yf4d2\" id=\"field_29yf4d2_label\" class=\"frm_primary_label\">Correo electr\u00f3nico\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input type=\"email\" id=\"field_29yf4d2\" name=\"item_meta[12]\" value=\"\"  placeholder=\"Correo electr\u00f3nico *\" data-reqmsg=\"Correo electr\u00f3nico no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Por favor, introduce una direcci\u00f3n de correo electr\u00f3nico v\u00e1lida\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_13_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container\">\r\n\t<label for=\"field_38myn2\" id=\"field_38myn2_label\" class=\"frm_primary_label\">Tel\u00e9fono\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<input type=\"tel\" id=\"field_38myn2\" name=\"item_meta[13]\" value=\"\"  placeholder=\"Tel\u00e9fono *\" data-reqmsg=\"Tel\u00e9fono no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Tel\u00e9fono no es v\u00e1lido\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_14_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container\">\r\n\t<label for=\"field_immjy2\" id=\"field_immjy2_label\" class=\"frm_primary_label\">Mensaje\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t<textarea data-auto-grow=\"1\"  name=\"item_meta[14]\" id=\"field_immjy2\" rows=\"1\"  placeholder=\"Mensaje *\" data-reqmsg=\"Mensaje no puede estar en blanco.\" aria-required=\"true\" data-invmsg=\"Mensaje no es v\u00e1lido\" aria-invalid=\"false\"  ><\/textarea>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_15_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container gdpr-check frm_first frm8 vertical_radio\">\r\n\t<div  id=\"field_lfz2l2_label\" class=\"frm_primary_label\">GDPR\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/div>\r\n\t<div class=\"frm_opt_container\" aria-labelledby=\"field_lfz2l2_label\" role=\"group\">\t\t<div class=\"frm_checkbox\" id=\"frm_checkbox_15-0\">\t\t\t<label  for=\"field_lfz2l2-0\">\n\t\t\t<input type=\"checkbox\" name=\"item_meta[15][]\" id=\"field_lfz2l2-0\" value=\"He le\u00eddo y acepto la &lt;a href=&quot;\/es\/politica-de-privacidad\/&quot; target=&quot;_blank&quot;&gt;pol\u00edtica de privacidad.&lt;\/a&gt;\"  data-reqmsg=\"GDPR no puede estar en blanco.\" data-invmsg=\"GDPR no es v\u00e1lido\"   aria-required=\"true\"  \/> He le\u00eddo y acepto la <a href=\"\/es\/politica-de-privacidad\/\" target=\"_blank\">pol\u00edtica de privacidad.<\/a><\/label><\/div>\n<\/div>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_16_container\" class=\"frm_form_field form-field  frm_alignright frm4\">\r\n\t<div class=\"frm_submit frm_flex\">\r\n<button class=\"frm_button_submit frm_final_submit button primary\" type=\"submit\"   formnovalidate=\"formnovalidate\"><span>Enviar<\/span><\/button>\r\n\r\n\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_17_container\">\n\t\t\t<label for=\"field_w0rg\" >\n\t\t\t\tSi eres humano, deja este campo en blanco.\t\t\t<\/label>\n\t\t\t<input  id=\"field_w0rg\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[17]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"cK9b+tvpuP1NX3dfpUJ\/VatLoikdLmGLAUX9TpXztCUc73R\/5EfNr+5ukJ1FiuMM\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1492021551 > .col-inner {\n  padding: 30px 30px 20px 30px;\n}\n@media (min-width:550px) {\n  #col-1492021551 > .col-inner {\n    padding: 50px 50px 20px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1982164656 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 0px;\n  background-color: rgba(0, 0, 0, 0.2);\n}\n<\/style>\n\t<\/section>\n\t\n\t<div id=\"gap-66047684\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-66047684 {\n  padding-top: 80px;\n}\n@media (min-width:550px) {\n  #gap-66047684 {\n    padding-top: 140px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<section class=\"section\" id=\"section_1821301618\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1935455249\">\n\n\t<div id=\"col-1068729951\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-640545638\" class=\"text italic txt-m-0\">\n\t\t\n<p data-animate=\"fadeIn\">Descubre todas nuestras creaciones.<br \/>Diferentes formas, una sola esencia.<\/p>\n\t\t\n<style>\n#text-640545638 {\n  font-size: 1.5rem;\n  line-height: 1.2;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-640545638 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1068729951 > .col-inner {\n  margin: 0px 0px 40px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1821980843\">\n\n\t<div id=\"col-1204629835\" class=\"col product-col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1875168407\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"415\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/elixir-image.jpg\" class=\"bg attachment-large size-large\" alt=\"Leyenda de olivo Aceite Elixir\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"\/es\/aceite-oliva-farga-milenario-elixir-30-ml\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-128795857\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-128795857 {\n  width: 60%;\n}\n#text-box-128795857 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-128795857 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1875168407 {\n  padding-top: 113.86%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover banner-hover\" id=\"banner-494001330\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"415\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/elixir-hover-image.jpg\" class=\"bg attachment-large size-large\" alt=\"Elixir Aceite de Oliva\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"\/es\/aceite-oliva-farga-milenario-elixir-30-ml\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1319709367\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1319709367 {\n  width: 60%;\n}\n#text-box-1319709367 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1319709367 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-494001330 {\n  padding-top: 113.86%;\n}\n<\/style>\n  <\/div>\n\n\n\t<div id=\"text-792067375\" class=\"text italic txt-m-0\">\n\t\t\n<h3><a href=\"\/es\/aceite-oliva-farga-milenario-elixir-30-ml\/\">Elixir<span class=\"small-text\">30 ml | Aceite de Oliva Farga Milenario<\/span><\/a><\/h3>\n\t\t\n<style>\n#text-792067375 {\n  font-size: 1.85rem;\n  line-height: 1.1;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-792067375 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1204629835 > .col-inner {\n  margin: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-638122092\" class=\"col product-col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-1407384103\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"415\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/farga-image2.jpg\" class=\"bg attachment-large size-large\" alt=\"Farga Premium Olive Oil\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"\/es\/aceite-oliva-virgen-extra-farga-100-ml\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1922957220\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1922957220 {\n  width: 60%;\n}\n#text-box-1922957220 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1922957220 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1407384103 {\n  padding-top: 113.86%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover banner-hover\" id=\"banner-68388689\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"415\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/farga-100-hover-image.jpg\" class=\"bg attachment-large size-large\" alt=\"Farga Premium Olive Oil\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"\/es\/aceite-oliva-virgen-extra-farga-100-ml\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-658630621\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-658630621 {\n  width: 60%;\n}\n#text-box-658630621 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-658630621 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-68388689 {\n  padding-top: 113.86%;\n}\n<\/style>\n  <\/div>\n\n\n\t<div id=\"text-1616332182\" class=\"text italic txt-m-0\">\n\t\t\n<h3><a href=\"\/es\/aceite-oliva-virgen-extra-farga-100-ml\/\">Farga <span class=\"small-text\">100 ml | Aceite de oliva virgen extra<br \/>\n<\/span><\/a><\/h3>\n\t\t\n<style>\n#text-1616332182 {\n  font-size: 1.85rem;\n  line-height: 1.1;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-1616332182 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-638122092 > .col-inner {\n  margin: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1705950045\" class=\"col product-col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-933486867\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"415\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/farga-image.jpg\" class=\"bg attachment-original size-original\" alt=\"big bottle olive oil Farga\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"\/es\/aceite-oliva-virgen-extra-farga-500-ml\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-627993216\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-627993216 {\n  width: 60%;\n}\n#text-box-627993216 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-627993216 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-933486867 {\n  padding-top: 113.86%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover banner-hover\" id=\"banner-1563610434\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"415\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/farga-500-hover-image.jpg\" class=\"bg attachment-original size-original\" alt=\"Extra virgin olive oil Farga\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"\/es\/aceite-oliva-virgen-extra-farga-500-ml\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-73619195\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-73619195 {\n  width: 60%;\n}\n#text-box-73619195 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-73619195 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1563610434 {\n  padding-top: 113.86%;\n}\n<\/style>\n  <\/div>\n\n\n\t<div id=\"text-572366849\" class=\"text italic txt-m-0\">\n\t\t\n<h3><a href=\"\/es\/aceite-oliva-virgen-extra-farga-500-ml\/\">Farga <span class=\"small-text\">500 ml | Aceite de oliva virgen extra<br \/>\n<\/span><\/a><\/h3>\n\t\t\n<style>\n#text-572366849 {\n  font-size: 1.85rem;\n  line-height: 1.1;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-572366849 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1705950045 > .col-inner {\n  margin: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-550661169\" class=\"col product-col medium-6 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-8001014\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"415\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/royal-image.jpg\" class=\"bg attachment-original size-original\" alt=\"Royal 500 ml Millenary Farga Olive Oil\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"\/es\/aceite-oliva-farga-milenario-royal-500-ml\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1919993341\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1919993341 {\n  width: 60%;\n}\n#text-box-1919993341 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1919993341 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-8001014 {\n  padding-top: 113.86%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover banner-hover\" id=\"banner-1871278366\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"415\" src=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/royal-hover-image.jpg\" class=\"bg attachment-original size-original\" alt=\"Royal\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"\/es\/aceite-oliva-farga-milenario-royal-500-ml\/\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1951118070\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1951118070 {\n  width: 60%;\n}\n#text-box-1951118070 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1951118070 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1871278366 {\n  padding-top: 113.86%;\n}\n<\/style>\n  <\/div>\n\n\n\t<div id=\"text-843960933\" class=\"text italic txt-m-0\">\n\t\t\n<h3><a href=\"\/es\/aceite-oliva-farga-milenario-royal-500-ml\/\">Royal <span class=\"small-text\">500 ml | Aceite de Oliva Farga Milenario<br \/>\n<\/span><\/a><\/h3>\n\t\t\n<style>\n#text-843960933 {\n  font-size: 1.85rem;\n  line-height: 1.1;\n  text-align: center;\n}\n@media (min-width:550px) {\n  #text-843960933 {\n    font-size: 2rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-550661169 > .col-inner {\n  margin: 0px 0px 20px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1821301618 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":643,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-683","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aceite de Oliva Farga 500 ml - Milenario | Leyenda de Olivo<\/title>\n<meta name=\"description\" content=\"Prueba el Aceite de Oliva Virgen Extra Farga Milenario 500 ml de Leyenda de Olivo. Un aceite lujoso de olivos Farga, ofreciendo un sabor suave y robusto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aceite de Oliva Farga 500 ml - Milenario | Leyenda de Olivo\" \/>\n<meta property=\"og:description\" content=\"Prueba el Aceite de Oliva Virgen Extra Farga Milenario 500 ml de Leyenda de Olivo. Un aceite lujoso de olivos Farga, ofreciendo un sabor suave y robusto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/\" \/>\n<meta property=\"og:site_name\" content=\"Leyenda de Olivo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leyendadeolivo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T12:35:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-right.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/aceite-oliva-farga-milenario-500-ml\\\/\",\"url\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/aceite-oliva-farga-milenario-500-ml\\\/\",\"name\":\"Aceite de Oliva Farga 500 ml - Milenario | Leyenda de Olivo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/aceite-oliva-farga-milenario-500-ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/aceite-oliva-farga-milenario-500-ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leyendadeolivo.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/milenario-image-right.jpg\",\"datePublished\":\"2025-10-20T13:38:46+00:00\",\"dateModified\":\"2025-11-14T12:35:55+00:00\",\"description\":\"Prueba el Aceite de Oliva Virgen Extra Farga Milenario 500 ml de Leyenda de Olivo. Un aceite lujoso de olivos Farga, ofreciendo un sabor suave y robusto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/aceite-oliva-farga-milenario-500-ml\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/aceite-oliva-farga-milenario-500-ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/aceite-oliva-farga-milenario-500-ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leyendadeolivo.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/milenario-image-right.jpg\",\"contentUrl\":\"https:\\\/\\\/leyendadeolivo.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/milenario-image-right.jpg\",\"width\":960,\"height\":1200,\"caption\":\"Milenario 500 ml Millenary Farga Olive Oil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/aceite-oliva-farga-milenario-500-ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Milenario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/\",\"name\":\"Leyenda de Olivo\",\"description\":\"The luxury of the essential. The purity of the eternal.\",\"publisher\":{\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/#organization\"},\"alternateName\":\"Leyenda de Olivo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/#organization\",\"name\":\"Leyenda del Olivo\",\"alternateName\":\"Leyenda del Olivo\",\"url\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leyendadeolivo.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo-header.svg\",\"contentUrl\":\"https:\\\/\\\/leyendadeolivo.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo-header.svg\",\"width\":1,\"height\":1,\"caption\":\"Leyenda del Olivo\"},\"image\":{\"@id\":\"https:\\\/\\\/leyendadeolivo.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leyendadeolivo\",\"https:\\\/\\\/www.instagram.com\\\/leyendadeolivo\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aceite de Oliva Farga 500 ml - Milenario | Leyenda de Olivo","description":"Prueba el Aceite de Oliva Virgen Extra Farga Milenario 500 ml de Leyenda de Olivo. Un aceite lujoso de olivos Farga, ofreciendo un sabor suave y robusto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/","og_locale":"es_ES","og_type":"article","og_title":"Aceite de Oliva Farga 500 ml - Milenario | Leyenda de Olivo","og_description":"Prueba el Aceite de Oliva Virgen Extra Farga Milenario 500 ml de Leyenda de Olivo. Un aceite lujoso de olivos Farga, ofreciendo un sabor suave y robusto.","og_url":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/","og_site_name":"Leyenda de Olivo","article_publisher":"https:\/\/www.facebook.com\/leyendadeolivo","article_modified_time":"2025-11-14T12:35:55+00:00","og_image":[{"width":960,"height":1200,"url":"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-right.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/","url":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/","name":"Aceite de Oliva Farga 500 ml - Milenario | Leyenda de Olivo","isPartOf":{"@id":"https:\/\/leyendadeolivo.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/#primaryimage"},"image":{"@id":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/#primaryimage"},"thumbnailUrl":"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-right.jpg","datePublished":"2025-10-20T13:38:46+00:00","dateModified":"2025-11-14T12:35:55+00:00","description":"Prueba el Aceite de Oliva Virgen Extra Farga Milenario 500 ml de Leyenda de Olivo. Un aceite lujoso de olivos Farga, ofreciendo un sabor suave y robusto.","breadcrumb":{"@id":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/#primaryimage","url":"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-right.jpg","contentUrl":"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/milenario-image-right.jpg","width":960,"height":1200,"caption":"Milenario 500 ml Millenary Farga Olive Oil"},{"@type":"BreadcrumbList","@id":"https:\/\/leyendadeolivo.com\/es\/aceite-oliva-farga-milenario-500-ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/leyendadeolivo.com\/es\/"},{"@type":"ListItem","position":2,"name":"Milenario"}]},{"@type":"WebSite","@id":"https:\/\/leyendadeolivo.com\/es\/#website","url":"https:\/\/leyendadeolivo.com\/es\/","name":"Leyenda de Olivo","description":"The luxury of the essential. The purity of the eternal.","publisher":{"@id":"https:\/\/leyendadeolivo.com\/es\/#organization"},"alternateName":"Leyenda de Olivo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leyendadeolivo.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/leyendadeolivo.com\/es\/#organization","name":"Leyenda del Olivo","alternateName":"Leyenda del Olivo","url":"https:\/\/leyendadeolivo.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/leyendadeolivo.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/logo-header.svg","contentUrl":"https:\/\/leyendadeolivo.com\/wp-content\/uploads\/2025\/10\/logo-header.svg","width":1,"height":1,"caption":"Leyenda del Olivo"},"image":{"@id":"https:\/\/leyendadeolivo.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leyendadeolivo","https:\/\/www.instagram.com\/leyendadeolivo\/"]}]}},"_links":{"self":[{"href":"https:\/\/leyendadeolivo.com\/es\/wp-json\/wp\/v2\/pages\/683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leyendadeolivo.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/leyendadeolivo.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/leyendadeolivo.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leyendadeolivo.com\/es\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":12,"href":"https:\/\/leyendadeolivo.com\/es\/wp-json\/wp\/v2\/pages\/683\/revisions"}],"predecessor-version":[{"id":884,"href":"https:\/\/leyendadeolivo.com\/es\/wp-json\/wp\/v2\/pages\/683\/revisions\/884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leyendadeolivo.com\/es\/wp-json\/wp\/v2\/media\/643"}],"wp:attachment":[{"href":"https:\/\/leyendadeolivo.com\/es\/wp-json\/wp\/v2\/media?parent=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}